{"id":404259,"date":"2026-05-29T19:49:32","date_gmt":"2026-05-29T17:49:32","guid":{"rendered":"https:\/\/maisoncleo.com\/?post_type=product&#038;p=404259"},"modified":"2026-08-26T12:45:35","modified_gmt":"2026-08-26T10:45:35","slug":"fw22-runway-look-23-jupe-longue-en-mesh-motif-roses-rouges-blair-copie","status":"publish","type":"product","link":"https:\/\/maisoncleo.com\/fr\/shop\/fw22-runway-look-23-jupe-longue-en-mesh-motif-roses-rouges-blair-copie\/","title":{"rendered":"READY-TO-SHIP &#8211; Jupe longue en mesh motif roses rouges BLAIR"},"content":{"rendered":"<p>Jupe longue en mesh motif roses rouges.<\/p>\n<p>Finition bourdon rouge sur ourlet. Stretch. Fente dans le milieu bas du dos.<\/p>\n<p>Tissus mesh \u00e0 roses rouges en collaboration avec l&rsquo;artiste peintre belge Stevie Dix. Design\u00a0unique !<\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Mini-jupe marron. Taille basse. nnFermeture \u00e9clair sur le c\u00f4t\u00e9. 100% cuir.nnComme tout est fait sur commande, vous pouvez demander la longueur que vous souhaitez et nous \u00e9crire un message durant ou suivant votre commande.nnLongueur standard \u00e0 plat :nnLOOK 1 de notre d\u00e9fil\u00e9 de mode &quot;L'Affranchie&quot; de septembre 2022.nnLa mod\u00e8le mesure 172 cm et porte une taille S-36. &quot;}\" data-sheets-userformat=\"{&quot;2&quot;:513,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0}\">Longueur standard \u00e0 plat : 100 cm.<\/span><\/p>\n<p>Longueur fente \u00e0 plat : 43 cm.<\/p>\n<p>LOOK 23 de notre d\u00e9fil\u00e9 automne hiver \u00ab\u00a0L&rsquo;Affranchie\u00a0\u00bb de septembre 2022.<\/p>\n<p>La mod\u00e8le mesure 172 cm et porte une taille S-36.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jupe longue en mesh motif roses rouges. Finition bourdon rouge sur ourlet. Stretch. Fente dans le milieu bas du dos. Tissus mesh&hellip;<\/p>\n","protected":false},"featured_media":345289,"template":"","meta":[],"product_brand":[],"product_cat":[913],"product_tag":[],"class_list":{"0":"post-404259","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ready-to-ship","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/product\/404259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/product\/404259\/revisions"}],"predecessor-version":[{"id":404268,"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/product\/404259\/revisions\/404268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/media\/345289"}],"wp:attachment":[{"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/media?parent=404259"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/product_brand?post=404259"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/product_cat?post=404259"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/maisoncleo.com\/fr\/wp-json\/wp\/v2\/product_tag?post=404259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}